{"id":4345,"date":"2026-02-16T12:53:47","date_gmt":"2026-02-16T12:53:47","guid":{"rendered":"https:\/\/www.ingegneriadelsole.it\/download\/"},"modified":"2026-02-16T19:07:22","modified_gmt":"2026-02-16T19:07:22","slug":"download","status":"publish","type":"page","link":"https:\/\/www.ingegneriadelsole.it\/en\/download\/","title":{"rendered":"Download"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:31px;--awb-padding-right:7px;--awb-padding-bottom:0px;--awb-padding-top-medium:90px;--awb-padding-bottom-medium:90px;--awb-padding-top-small:10px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-margin-bottom-medium:0px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column fusion-flex-align-self-flex-start fusion-column-no-min-height fusion-animated\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:75%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.56%;--awb-margin-bottom-large:60px;--awb-spacing-left-large:2.56%;--awb-width-medium:80%;--awb-spacing-right-medium:2.4%;--awb-spacing-left-medium:2.4%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeIn\" data-animationDuration=\"0.8\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"--awb-content-alignment:center;--awb-font-size:var(--awb-typography3-font-size);--awb-line-height:var(--awb-typography3-line-height);--awb-letter-spacing:var(--awb-typography3-letter-spacing);--awb-text-transform:var(--awb-typography3-text-transform);--awb-text-color:var(--awb-color6);--awb-text-font-family:var(--awb-typography3-font-family);--awb-text-font-weight:var(--awb-typography3-font-weight);--awb-text-font-style:var(--awb-typography3-font-style);\"><p>Solar Engineering<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.88%;--awb-width-medium:66.666666666667%;--awb-order-medium:0;--awb-spacing-right-medium:2.88%;--awb-spacing-left-medium:2.88%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p>In this section, you can download industry-specific documents of interest, such as regulations, guidelines, technical studies, and useful materials for learning more about the world of energy, plant engineering, and renewables.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-flex-column fusion-flex-align-self-center fusion-animated\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-transform:translateY(0px);--awb-transform-hover:translateY(-5px);--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.5px;--awb-margin-bottom-large:110px;--awb-spacing-left-large:7.5px;--awb-width-medium:33.333333333333%;--awb-spacing-right-medium:7.5px;--awb-margin-bottom-medium:70px;--awb-spacing-left-medium:7.5px;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:50px;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInUp\" data-animationDuration=\"0.8\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"wpfd-content wpfd-content-default wpfd-content-category-normal wpfd-content-multi\" data-category=\"164\"             style=\"background-color: rgba(255, 255, 255, 0)\"><input type=\"hidden\" id=\"current_category_164\" value=\"164\" \/>                    <input type=\"hidden\" id=\"current_category_slug_164\" value=\"download\" \/>                    <input type=\"hidden\" id=\"current_ordering_164\" value=\"description\" \/>                    <input type=\"hidden\" id=\"current_ordering_direction_164\" value=\"desc\" \/>                    <input type=\"hidden\" id=\"page_limit_164\" value=\"-1\" \/><input type=\"hidden\" id=\"wpfd_display_empty_category_message\" value=\"0\" \/><input type=\"hidden\" id=\"wpfd_empty_category_message_val\" value=\"Questa categoria non ha file da visualizzare\" \/><input type=\"hidden\" id=\"wpfd_display_empty_folder\" value=\"1\" \/><input type=\"hidden\" id=\"wpfd_is_empty_subcategories\" value=\"1\" \/><input type=\"hidden\" id=\"wpfd_is_empty_files\" value=\"1\" \/><input type=\"hidden\" id=\"wpfd_root_category_id\" class=\"wpfd_root_category_id\" value=\"164\" \/><input type=\"hidden\" id=\"wpfd_root_category_theme\" class=\"wpfd_root_category_theme\" value=\"default\" \/><input type=\"hidden\" id=\"wpfd_root_category_clone_theme_type\" class=\"wpfd_root_category_clone_theme_type\" value=\"none\" \/><input type=\"hidden\" id=\"wpfd_root_category_type\" class=\"wpfd_root_category_type\" value=\"164\" \/><input type=\"hidden\" id=\"wpfd_category_notify_file_changes\" class=\"wpfd_category_notify_file_changes\" value=\"0\" \/><input type=\"hidden\" id=\"wpfd_global_notify_file_changes\" class=\"wpfd_global_notify_file_changes\" value=\"0\" \/><input type=\"hidden\" id=\"wpfd_download_selected\" class=\"wpfd_download_selected\" value=\"1\" \/><input type=\"hidden\" id=\"wpfd_user_login\" class=\"wpfd_user_login\" value=\"0\" \/><div class=\"wpfd-content-header-section\"><div class=\"wpfd-header-btn-group\"><a class=\"wpfd-category-mail-subscribe-all\" href=\"#\" style=\"display: none\">Email Subscribe All<\/a><a data-catid=\"\" class=\"default-download-category \" href=\"https:\/\/www.ingegneriadelsole.it\/download\/wpfdcat\/164\/download\">Download all                                 <i class=\"zmdi zmdi-check-all wpfd-download-category\"><\/i>                            <\/a><\/div><ul class=\"breadcrumbs wpfd-breadcrumbs-default head-category-default\">                            <li class=\"active\">DOWNLOAD<\/li>                        <\/ul><\/div>    <script type=\"text\/x-handlebars-template\" class=\"wpfd-template-categories\">        <div class=\"wpfd-categories \">{{#if category}}{{#with category}}<h2>{{name}}<\/h2>{{#if parent}}<a class=\"catlink backcategory\" href=\"#\" data-idcat=\"{{parent}}\">                        <i class=\"zmdi zmdi-chevron-left\"><\/i><span>Back<\/span><\/a>{{\/if}}{{\/with}}{{\/if}}{{#if category.desc}}<div class=\"wpfd-category-desc\">{{category.desc}}<\/div>{{\/if}}{{#if categories}}{{#each categories}}<a class=\"wpfdcategory catlink \" style=\"margin : 7px 10px 7px 10px;\" href=\"#\" data-idcat=\"{{termID}}\" title=\"{{name}}\">                                <span>{{name}}<\/span><i class=\"zmdi zmdi-folder wpfd-folder\" style=\"color: {{color}}\"><\/i>                            <\/a>{{\/each}}{{\/if}}<div class=\"wpfdcategory_placeholder\" style=\"margin : 0 10px 0 10px;\"><\/div><div class=\"wpfdcategory_placeholder\" style=\"margin : 0 10px 0 10px;\"><\/div><div class=\"wpfdcategory_placeholder\" style=\"margin : 0 10px 0 10px;\"><\/div><\/div>    <\/script>    <script type=\"text\/x-handlebars-template\" class=\"wpfd-template-files\">        {{#if files }}        <div class=\"wpfd_list\">            {{#each files}}            <div class=\"file {{ext}}\" style=\"margin : 7px 10px 7px 10px;\" data-id=\"{{ID}}\" data-catid=\"{{catid}}\">                <input type=\"hidden\" class=\"wpfd_file_preview_link_download\" value=\"{{linkdownload}}\" data-filetitle=\"{{post_title}}\" data-fileicons=\"ext ext-{{ext}} wpfd-icon-set-svg\" \/>                <div class=\"filecontent\">                    <div class=\"ext ext-{{ext}} wpfd-icon-set-svg\"><span class=\"txt\">{{ext}}<\/span><\/div><h3><label class=\"wpfd_checkbox\"><input class=\"cbox_file_download\" type=\"checkbox\" data-id=\"{{ID}}\" \/><span><\/span><\/label><a href=\"{{linkdownload}}\"  rel=\"nofollow\"   class=\"wpfd_downloadlink\" title=\"{{post_title}}\" target=\"{{#if remote_file}}_blank{{\/if}}\">{{{crop_title}}}<\/a><\/h3>                    <div class=\"file-xinfo\">                        {{#if description}}<div class=\"file-desc\">{{{description}}}<\/div>{{\/if}}{{#if versionNumber}}<div class=\"file-version\"><span>Version:<\/span> {{versionNumber}}<\/div>{{\/if}}<div class=\"file-size\"><span>Size:<\/span> {{bytesToSize size}}<\/div>                    <\/div>                <\/div>                <span class=\"file-right\">                    <a class=\"downloadlink wpfd_downloadlink\"  href=\"{{linkdownload}}\"  rel=\"nofollow\"  style=\"background-color:#76bc58;color:#ffffff;\" target=\"{{#if remote_file}}_blank{{\/if}}\">Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>                <\/span>            <\/div>            {{\/each}}            <div class=\"file flex_span\" style=\"margin : 7px 10px 7px 10px;\"><\/div>        <\/div>        {{\/if}}    <\/script>    <div class=\"wpfd-container show_category_title show_breadcrumb show_subcategories folder-tree-left\">        <div class=\"wpfd-foldertree wpfd-foldertree-default foldertree-hide\"><\/div>        <div class=\"wpfd-open-tree\"><\/div>        <div class=\"wpfd-container-default  with_foldertree\">            <div class=\"wpfd-categories \"><h2 class=\"wpfd-category-theme-title\">DOWNLOAD<\/h2><div class=\"wpfd-category-desc\"><\/div><\/div>                            <div class=\"wpfd_list\">                                                                        <div class=\"file pdf\" style=\"margin : 7px 10px 7px 10px;\"                                 data-id=\"4357\"                                 data-catid=\"164\">                                                                <input type=\"hidden\" class=\"wpfd_file_preview_link_download\" value=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4357\/arera-testo-aggiornato-385.pdf\"                                       data-filetitle=\"ARERA - Testo Aggiornato 385\" data-fileicons=\"ext ext-pdf wpfd-icon-set-svg\" \/>                                <div class=\"filecontent\">                                    <div class=\"ext ext-pdf wpfd-icon-set-svg\"><span class=\"txt\">pdf<\/span><\/div><h3><label class=\"wpfd_checkbox\"><input class=\"cbox_file_download\" type=\"checkbox\" data-id=\"4357\" data-catid=\"164\" \/><span><\/span><\/label><a href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4357\/arera-testo-aggiornato-385.pdf\"  rel=\"nofollow\"   class=\"wpfd_downloadlink\" title=\"ARERA - Testo Aggiornato 385\" target=\"\">ARERA - Testo Aggiornato 385<\/a><\/h3>                                    <div class=\"file-xinfo\">                                        <div class=\"file-desc\">Testo coordinato delle integrazioni e modifiche apportate con la deliberazione 564\/2025\/R\/EEL<\/div><div class=\"file-size\"><span>Size:<\/span> 374.93 KB<\/div>                                    <\/div>                                <\/div>                                <div class=\"file-right\">                                    <a class=\"downloadlink wpfd_downloadlink\"  href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4357\/arera-testo-aggiornato-385.pdf\"  rel=\"nofollow\"  style=\"background-color:#76bc58;color:#ffffff;\" target=\"\">Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>                                <\/div>                            <\/div>                                                                                                <div class=\"file pdf\" style=\"margin : 7px 10px 7px 10px;\"                                 data-id=\"4369\"                                 data-catid=\"164\">                                                                <input type=\"hidden\" class=\"wpfd_file_preview_link_download\" value=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4369\/arera-421-teledistacco.pdf\"                                       data-filetitle=\"ARERA - 421 Teledistacco\" data-fileicons=\"ext ext-pdf wpfd-icon-set-svg\" \/>                                <div class=\"filecontent\">                                    <div class=\"ext ext-pdf wpfd-icon-set-svg\"><span class=\"txt\">pdf<\/span><\/div><h3><label class=\"wpfd_checkbox\"><input class=\"cbox_file_download\" type=\"checkbox\" data-id=\"4369\" data-catid=\"164\" \/><span><\/span><\/label><a href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4369\/arera-421-teledistacco.pdf\"  rel=\"nofollow\"   class=\"wpfd_downloadlink\" title=\"ARERA - 421 Teledistacco\" target=\"\">ARERA - 421 Teledistacco<\/a><\/h3>                                    <div class=\"file-xinfo\">                                        <div class=\"file-desc\">Testo coordinato con le integrazioni e modifiche apportate dalla deliberazione 79\/2015\/R\/eel<\/div><div class=\"file-size\"><span>Size:<\/span> 90.96 KB<\/div>                                    <\/div>                                <\/div>                                <div class=\"file-right\">                                    <a class=\"downloadlink wpfd_downloadlink\"  href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4369\/arera-421-teledistacco.pdf\"  rel=\"nofollow\"  style=\"background-color:#76bc58;color:#ffffff;\" target=\"\">Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>                                <\/div>                            <\/div>                                                                                                <div class=\"file pdf\" style=\"margin : 7px 10px 7px 10px;\"                                 data-id=\"4371\"                                 data-catid=\"164\">                                                                <input type=\"hidden\" class=\"wpfd_file_preview_link_download\" value=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4371\/adm-circolare-32-20025.pdf\"                                       data-filetitle=\"ADM - Circolare 32-20025\" data-fileicons=\"ext ext-pdf wpfd-icon-set-svg\" \/>                                <div class=\"filecontent\">                                    <div class=\"ext ext-pdf wpfd-icon-set-svg\"><span class=\"txt\">pdf<\/span><\/div><h3><label class=\"wpfd_checkbox\"><input class=\"cbox_file_download\" type=\"checkbox\" data-id=\"4371\" data-catid=\"164\" \/><span><\/span><\/label><a href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4371\/adm-circolare-32-20025.pdf\"  rel=\"nofollow\"   class=\"wpfd_downloadlink\" title=\"ADM - Circolare 32-20025\" target=\"\">ADM - Circolare 32-20025<\/a><\/h3>                                    <div class=\"file-xinfo\">                                        <div class=\"file-desc\">Modifiche alla disciplina delle accise. Revisione<\/div><div class=\"file-size\"><span>Size:<\/span> 1.03 MB<\/div>                                    <\/div>                                <\/div>                                <div class=\"file-right\">                                    <a class=\"downloadlink wpfd_downloadlink\"  href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4371\/adm-circolare-32-20025.pdf\"  rel=\"nofollow\"  style=\"background-color:#76bc58;color:#ffffff;\" target=\"\">Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>                                <\/div>                            <\/div>                                                                                                <div class=\"file pdf\" style=\"margin : 7px 10px 7px 10px;\"                                 data-id=\"4370\"                                 data-catid=\"164\">                                                                <input type=\"hidden\" class=\"wpfd_file_preview_link_download\" value=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4370\/adm-circolare-13-2025.pdf\"                                       data-filetitle=\"ADM - Circolare 13-2025\" data-fileicons=\"ext ext-pdf wpfd-icon-set-svg\" \/>                                <div class=\"filecontent\">                                    <div class=\"ext ext-pdf wpfd-icon-set-svg\"><span class=\"txt\">pdf<\/span><\/div><h3><label class=\"wpfd_checkbox\"><input class=\"cbox_file_download\" type=\"checkbox\" data-id=\"4370\" data-catid=\"164\" \/><span><\/span><\/label><a href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4370\/adm-circolare-13-2025.pdf\"  rel=\"nofollow\"   class=\"wpfd_downloadlink\" title=\"ADM - Circolare 13-2025\" target=\"\">ADM - Circolare 13-2025<\/a><\/h3>                                    <div class=\"file-xinfo\">                                        <div class=\"file-desc\">Modifiche alla disciplina delle accise. Prime Indicazioni<\/div><div class=\"file-size\"><span>Size:<\/span> 357.12 KB<\/div>                                    <\/div>                                <\/div>                                <div class=\"file-right\">                                    <a class=\"downloadlink wpfd_downloadlink\"  href=\"https:\/\/www.ingegneriadelsole.it\/download\/164\/download\/4370\/adm-circolare-13-2025.pdf\"  rel=\"nofollow\"  style=\"background-color:#76bc58;color:#ffffff;\" target=\"\">Download<i class=\"zmdi zmdi-cloud-download wpfd-download\"><\/i><\/a>                                <\/div>                            <\/div>                                                                <div class=\"file flex_span\" style=\"margin : 7px 10px 7px 10px;\"><\/div>                <\/div>                                <\/div>    <\/div><\/div>\n\n\n\n\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3152,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-4345","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Download - Ingegneria del sole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ingegneriadelsole.it\/en\/download\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Download\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ingegneriadelsole.it\/en\/download\/\" \/>\n<meta property=\"og:site_name\" content=\"Ingegneria del sole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ingegneriadelsole\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T19:07:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/sede-copia-e1769434946594.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1968\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/\",\"url\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/\",\"name\":\"Download - Ingegneria del sole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sede-copia-e1769434946594.jpg\",\"datePublished\":\"2026-02-16T12:53:47+00:00\",\"dateModified\":\"2026-02-16T19:07:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sede-copia-e1769434946594.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sede-copia-e1769434946594.jpg\",\"width\":1968,\"height\":945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/download\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Download\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/\",\"name\":\"Ingegneria del sole\",\"description\":\"soluzioni per un futuro ecosostenibile\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/#organization\",\"name\":\"Ingegneria del sole\",\"url\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Senza-titolo.png\",\"contentUrl\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Senza-titolo.png\",\"width\":507,\"height\":73,\"caption\":\"Ingegneria del sole\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ingegneriadelsole.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ingegneriadelsole\",\"https:\\\/\\\/www.instagram.com\\\/ingegneriadelsole\"],\"description\":\"Ingegneria del sole, impianti fotovoltaici, analisi power quality, analisi techiche aeree, altr fonti rinnovabili\",\"email\":\"info@ingegneriadelsole.it\",\"telephone\":\"+39 08117780053\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Download - Ingegneria del sole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ingegneriadelsole.it\/en\/download\/","og_locale":"en_US","og_type":"article","og_title":"Download","og_url":"https:\/\/www.ingegneriadelsole.it\/en\/download\/","og_site_name":"Ingegneria del sole","article_publisher":"https:\/\/www.facebook.com\/ingegneriadelsole","article_modified_time":"2026-02-16T19:07:22+00:00","og_image":[{"width":1968,"height":945,"url":"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/sede-copia-e1769434946594.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ingegneriadelsole.it\/en\/download\/","url":"https:\/\/www.ingegneriadelsole.it\/en\/download\/","name":"Download - Ingegneria del sole","isPartOf":{"@id":"https:\/\/www.ingegneriadelsole.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ingegneriadelsole.it\/en\/download\/#primaryimage"},"image":{"@id":"https:\/\/www.ingegneriadelsole.it\/en\/download\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/sede-copia-e1769434946594.jpg","datePublished":"2026-02-16T12:53:47+00:00","dateModified":"2026-02-16T19:07:22+00:00","breadcrumb":{"@id":"https:\/\/www.ingegneriadelsole.it\/en\/download\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ingegneriadelsole.it\/en\/download\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ingegneriadelsole.it\/en\/download\/#primaryimage","url":"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/sede-copia-e1769434946594.jpg","contentUrl":"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/sede-copia-e1769434946594.jpg","width":1968,"height":945},{"@type":"BreadcrumbList","@id":"https:\/\/www.ingegneriadelsole.it\/en\/download\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ingegneriadelsole.it\/en\/"},{"@type":"ListItem","position":2,"name":"Download"}]},{"@type":"WebSite","@id":"https:\/\/www.ingegneriadelsole.it\/en\/#website","url":"https:\/\/www.ingegneriadelsole.it\/en\/","name":"Ingegneria del sole","description":"soluzioni per un futuro ecosostenibile","publisher":{"@id":"https:\/\/www.ingegneriadelsole.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ingegneriadelsole.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ingegneriadelsole.it\/en\/#organization","name":"Ingegneria del sole","url":"https:\/\/www.ingegneriadelsole.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ingegneriadelsole.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/Senza-titolo.png","contentUrl":"https:\/\/www.ingegneriadelsole.it\/wp-content\/uploads\/2026\/01\/Senza-titolo.png","width":507,"height":73,"caption":"Ingegneria del sole"},"image":{"@id":"https:\/\/www.ingegneriadelsole.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ingegneriadelsole","https:\/\/www.instagram.com\/ingegneriadelsole"],"description":"Ingegneria del sole, impianti fotovoltaici, analisi power quality, analisi techiche aeree, altr fonti rinnovabili","email":"info@ingegneriadelsole.it","telephone":"+39 08117780053"}]}},"_links":{"self":[{"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/pages\/4345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/comments?post=4345"}],"version-history":[{"count":1,"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/pages\/4345\/revisions"}],"predecessor-version":[{"id":4354,"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/pages\/4345\/revisions\/4354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/media\/3152"}],"wp:attachment":[{"href":"https:\/\/www.ingegneriadelsole.it\/en\/wp-json\/wp\/v2\/media?parent=4345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}